{"id":2139,"date":"2025-01-23T14:45:49","date_gmt":"2025-01-23T14:45:49","guid":{"rendered":"https:\/\/coaching.evylou.com\/deolontische-code\/"},"modified":"2025-03-31T11:44:06","modified_gmt":"2025-03-31T11:44:06","slug":"deolontische-code","status":"publish","type":"page","link":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/","title":{"rendered":"Deontologische code"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_heading title=&#8221;Wat is hypnose en de deontologische code?&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/coaching.evylou.com\/wp-content\/uploads\/2025\/01\/SUP_H_AFFICHE_BE_PRATICIENS_A4-pdf.jpg&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; title_text=&#8221;SUP_H_BE_PRAKTIJK_A4&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; column_structure=&#8221;1_3,1_3,1_3&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_3&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Deontologische code van het Syndicat unitaire des Professinels de l&#8217;Hypnose. <\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_3&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/coaching.evylou.com\/wp-content\/uploads\/2025\/01\/SUP_H_CHARTE_DEONTO_PROFESSIONNELS_HYPNOSE_2023-pdf.jpg&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; title_text=&#8221;SUP_H_CHARTE_DEONTO_PROFESSIONALS_HYPNOSE_2023&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_3&#8243; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deontologische code van het Syndicat unitaire des Professinels de l&#8217;Hypnose.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2139","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hypnose Bruxelles<\/title>\n<meta name=\"description\" content=\"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l&#039;hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd&#039;hui\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hypnose Bruxelles\" \/>\n<meta property=\"og:description\" content=\"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l&#039;hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd&#039;hui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/\" \/>\n<meta property=\"og:site_name\" content=\"Evylou coaching &amp; hypnose\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T11:44:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coaching.evylou.com\/wp-content\/uploads\/2024\/10\/logo-evylou-coaching.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1106\" \/>\n\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/deolontische-code\\\/\",\"url\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/deolontische-code\\\/\",\"name\":\"Hypnose Bruxelles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/#website\"},\"datePublished\":\"2025-01-23T14:45:49+00:00\",\"dateModified\":\"2025-03-31T11:44:06+00:00\",\"description\":\"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l'hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd'hui\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/deolontische-code\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/deolontische-code\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/deolontische-code\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deontologische code\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/\",\"name\":\"coaching.evylou.com\",\"description\":\"Hypnose en coaching\",\"publisher\":{\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/#\\\/schema\\\/person\\\/791818c5517a8da614542c7c926ed4c0\"},\"alternateName\":\"Evylou coaching - hypnose\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/coaching.evylou.com\\\/nl\\\/#\\\/schema\\\/person\\\/791818c5517a8da614542c7c926ed4c0\",\"name\":\"evylou de Vleeschouwer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g\",\"caption\":\"evylou de Vleeschouwer\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g\"},\"description\":\"coach de vie et hypnoth\u00e9rapeute\",\"sameAs\":[\"https:\\\/\\\/coaching.evylou.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hypnose Bruxelles","description":"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l'hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd'hui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/","og_locale":"nl_NL","og_type":"article","og_title":"Hypnose Bruxelles","og_description":"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l'hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd'hui","og_url":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/","og_site_name":"Evylou coaching & hypnose","article_modified_time":"2025-03-31T11:44:06+00:00","og_image":[{"width":1106,"height":733,"url":"https:\/\/coaching.evylou.com\/wp-content\/uploads\/2024\/10\/logo-evylou-coaching.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/","url":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/","name":"Hypnose Bruxelles","isPartOf":{"@id":"https:\/\/coaching.evylou.com\/nl\/#website"},"datePublished":"2025-01-23T14:45:49+00:00","dateModified":"2025-03-31T11:44:06+00:00","description":"Arr\u00eater de fumer, perdre du poids, g\u00e9rer son stress, surmonter ses peurs: l'hypnose \u00e0 Bruxelles peut aider \u00e0 changer votre quotidien aujourd'hui","breadcrumb":{"@id":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coaching.evylou.com\/nl\/deolontische-code\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coaching.evylou.com\/nl\/deolontische-code\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/coaching.evylou.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Deontologische code"}]},{"@type":"WebSite","@id":"https:\/\/coaching.evylou.com\/nl\/#website","url":"https:\/\/coaching.evylou.com\/nl\/","name":"coaching.evylou.com","description":"Hypnose en coaching","publisher":{"@id":"https:\/\/coaching.evylou.com\/nl\/#\/schema\/person\/791818c5517a8da614542c7c926ed4c0"},"alternateName":"Evylou coaching - hypnose","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coaching.evylou.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Person","Organization"],"@id":"https:\/\/coaching.evylou.com\/nl\/#\/schema\/person\/791818c5517a8da614542c7c926ed4c0","name":"evylou de Vleeschouwer","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g","caption":"evylou de Vleeschouwer"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/9d120b3b9a3a2c01fca281788b8000b664c22a9e7e36acc99cfd368f009faef0?s=96&d=mm&r=g"},"description":"coach de vie et hypnoth\u00e9rapeute","sameAs":["https:\/\/coaching.evylou.com"]}]}},"_links":{"self":[{"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/pages\/2139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/comments?post=2139"}],"version-history":[{"count":4,"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/pages\/2139\/revisions"}],"predecessor-version":[{"id":2154,"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/pages\/2139\/revisions\/2154"}],"wp:attachment":[{"href":"https:\/\/coaching.evylou.com\/nl\/wp-json\/wp\/v2\/media?parent=2139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}